{"id":49,"date":"2025-04-30T08:30:02","date_gmt":"2025-04-30T06:30:02","guid":{"rendered":"https:\/\/alexs-and-books.de\/reading\/?p=49"},"modified":"2025-12-10T06:41:33","modified_gmt":"2025-12-10T05:41:33","slug":"kristen-perrin-das-moerderarchiv","status":"publish","type":"post","link":"https:\/\/alexs-and-books.de\/reading\/kristen-perrin-das-moerderarchiv\/","title":{"rendered":"Kristen Perrin | Das M\u00f6rderarchiv"},"content":{"rendered":"<p>Deutsch, Teil 1 von 2, H\u00f6rbuch<\/p>\n<p><!--more--><\/p>\n<h3>Informationen<\/h3>\n<p><strong>Autorin: <\/strong>Kristen Perrin<\/p>\n<p><strong>Sprache: <\/strong>Deutsch<\/p>\n<p><strong>Gesprochen von:<\/strong> Anne D\u00fce<\/p>\n<p><strong>Titel: <\/strong>Das M\u00f6rderarchiv<\/p>\n<p><strong>Reihe\/Einzelband:<\/strong> Diologie, Band 1 von 2<\/p>\n<p><b>Dauer: <\/b>10 Stunden und 6 Minuten<\/p>\n<p><strong>Verlag: <\/strong>Argon Verlag<\/p>\n<p><strong>Ver\u00f6ffentlichung: <\/strong>Januar 2024<\/p>\n<p><strong>Gek\u00fcrzt\/Ungek\u00fcrzt:<\/strong> Ungek\u00fcrzt<\/p>\n<p>&nbsp;<\/p>\n<h3>Inhaltsangabe<\/h3>\n<p>Das sensationelle Krimi-Ereignis des Jahres zum Wohlf\u00fchlen, Schmunzeln und Mitr\u00e4tseln f\u00fcr alle Fans von Richard Osman und Robert Thorogood: Wie findet man den eigenen M\u00f6rder? Man legt ein Archiv an (und l\u00e4sst andere die Arbeit machen).<\/p>\n<p>Tante Frances dachte immer, dass sie eines Tages umgebracht wird. Sie hatte recht. Und sie hat vorgesorgt.<\/p>\n<p>Frances Adams war siebzehn Jahre alt, als eine Wahrsagerin ihr 1965 auf dem Jahrmarkt prophezeite, dass man sie ermorden w\u00fcrde. Ihr Leben lang nahm niemand Frances ernst. Bis sie sechzig Jahre sp\u00e4ter \u2013 wie k\u00f6nnte es anders sein? \u2013 ermordet wird! Tante Frances hatte also recht. Und sie hat vorgesorgt. Erstens legte sie auf ihrem herrschaftlichen Landgut in Dorset ein besonderes Archiv an. Jede Person aus dem Dorf, die sie auch nur im Entferntesten f\u00fcr verd\u00e4chtig hielt, taucht dort auf. Zweitens hinterlie\u00df sie ein Testament f\u00fcr Gro\u00dfnichte Annie und Stiefsohn Saxon: Wer den Mord aufl\u00f6st, erbt alles. Die angehende Krimiautorin oder der fiese Rechtsmediziner?<\/p>\n<p>Da Annie die schrullige alte Dame nie kennengelernt hat, scheint sie klar im Nachteil. Doch dann findet die clevere junge Frau ein Tagebuch der Tante und liest \u00fcber ein tragisches Ereignis in den Sechziger Jahren. Annie kombiniert: Unter mehr als einem Dach in Castle Knoll schlummert ein t\u00f6dliches Geheimnis. Nur unter welchen?<\/p>\n<p>Schlagfertig und unschlagbar: Eine Heldin zum Verlieben! Annie wird als Amateur-Ermittlerin das idyllische Castle Knoll auch in Folgeb\u00e4nden unter die Lupe nehmen.<\/p>\n<h3>Meine Gedanken<\/h3>\n<p class=\"\" data-start=\"142\" data-end=\"415\">Das H\u00f6rbuch habe ich auf Legimi geh\u00f6rt \u2013 mein erstes H\u00f6rbuch nach Jahren, und ich muss sagen: Besser h\u00e4tte der Einstieg ins H\u00f6rbuchh\u00f6ren nicht sein k\u00f6nnen. <em data-start=\"298\" data-end=\"316\">Das M\u00f6rderarchiv<\/em> wird von Anne D\u00fce angenehm vorgelesen. Sie hat den Schreibstil der Autorin sehr gut transportiert.<\/p>\n<p class=\"\" data-start=\"417\" data-end=\"600\"><em data-start=\"417\" data-end=\"435\">Das M\u00f6rderarchiv<\/em> wird aus zwei Perspektiven erz\u00e4hlt \u2013 eine schildert die Vergangenheit, die andere die Gegenwart. Die jeweiligen Charaktere bekommen ausreichend Raum zur Entfaltung.<\/p>\n<p class=\"\" data-start=\"602\" data-end=\"884\">Ich mag den Schreibstil. Die Dialoge waren gut nachvollziehbar und wirkten nat\u00fcrlich. Die Beschreibungen waren angenehm detailliert und vermittelten alles Notwendige, ohne dabei zu viel oder zu wenig preiszugeben. Ich konnte mich beim H\u00f6ren gewisserma\u00dfen einfach \u201eberieseln\u201c lassen.<\/p>\n<p class=\"\" data-start=\"886\" data-end=\"1177\">War es spannend? Nicht im klassischen Sinne. Zum Ende hin wurde es zwar etwas spannender \u2013 ganz im Stil eines typischen Krimis oder Thrillers \u2013 aber insgesamt w\u00fcrde ich das Buch eher als \u201eCozy Read\u201c bezeichnen. Trotz der teilweise gem\u00e4chlichen Erz\u00e4hlweise wurde ich durchweg gut unterhalten.<\/p>\n<p data-start=\"886\" data-end=\"1177\">Wer mitraten will, ist hier eher falsch aufgehoben: Ich habe zugegeben wirklich nur zugeh\u00f6rt und nebenbei zum Beispiel gezeichnet \u2013 dabei kamen mir aber keinerlei Gedanken zu einem m\u00f6glichen T\u00e4ter. Es kann durchaus sein, dass das beim aktiven Lesen oder aufmerksamen H\u00f6ren anders ist.<\/p>\n<p class=\"\" data-start=\"1179\" data-end=\"1276\">Kurzum: Das H\u00f6rbuch hat mich so \u00fcberzeugt, dass nun auch die Printausgabe bei mir einziehen darf \ud83d\ude0a<\/p>\n<h3>Bewertung<\/h3>\n<p><strong>Gesamt:<\/strong> <strong>\u2605\u2605\u2605\u2605\u2605 <\/strong>5 von 5<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deutsch, Teil 1 von 2, H\u00f6rbuch<\/p>\n","protected":false},"author":1,"featured_media":278,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[9,16],"class_list":["post-49","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-krimi-thriller","tag-deutsch","tag-hoerbuch"],"_links":{"self":[{"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/posts\/49","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/comments?post=49"}],"version-history":[{"count":4,"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/posts\/49\/revisions"}],"predecessor-version":[{"id":282,"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/posts\/49\/revisions\/282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/media\/278"}],"wp:attachment":[{"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/media?parent=49"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/categories?post=49"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/tags?post=49"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}