{"id":37,"date":"2025-02-28T13:21:42","date_gmt":"2025-02-28T12:21:42","guid":{"rendered":"https:\/\/alexs-and-books.de\/reading\/?p=37"},"modified":"2025-04-18T08:46:04","modified_gmt":"2025-04-18T06:46:04","slug":"lesemonat-februar-2025","status":"publish","type":"post","link":"https:\/\/alexs-and-books.de\/reading\/lesemonat-februar-2025\/","title":{"rendered":"Lesemonat | Februar 2025"},"content":{"rendered":"<p>Mein Februar Lesemonat ist da und ein bisschen Geplauder \u00fcber die Schm\u00f6kerbox (Preiserh\u00f6hung) und was sonst noch so war<\/p>\n<p><!--more--><\/p>\n<p class=\"LC20lb MBeuO DKV0Md\">\u2714\ufe0f = fertig gelesen, \u274c = abgebrochen \u2b50\ufe0f = 5 Sterne Read<\/p>\n<h3>Lesemonat<\/h3>\n<p><strong>B\u00fccher<\/strong><\/p>\n<p><strong>\u2714\ufe0f \u2b50\ufe0f Tr\u00edona Walsh<\/strong>\u00a0| DE | <a href=\"https:\/\/alexs-and-books.de\/reading\/triona-walsh-schneesturm\/?customize_changeset_uuid=16598e6e-f802-4e85-8d62-b6106f7f4d7b\" target=\"_blank\" rel=\"noopener\">Schneesturm<\/a> \/ Buddyread<\/p>\n<p><strong>\u2714\ufe0f \u2b50\ufe0f Ariel Lawhon<\/strong> | DE| <a href=\"https:\/\/alexs-and-books.de\/reading\/ariel-lawhon-der-gefrorene-fluss\/?customize_changeset_uuid=16598e6e-f802-4e85-8d62-b6106f7f4d7b\" target=\"_blank\" rel=\"noopener\">Der gefrorene Fluss<\/a><\/p>\n<p><strong>\u2714\ufe0f \u2b50\ufe0f Kerstin Ruhkieck<\/strong> | DE | <a href=\"https:\/\/alexs-and-books.de\/reading\/kerstin-ruhkieck-in-deinen-augen-der-tod\/?customize_changeset_uuid=16598e6e-f802-4e85-8d62-b6106f7f4d7b\" target=\"_blank\" rel=\"noopener\">In deinen Augen der Tod<\/a><\/p>\n<p><strong>\u2714\ufe0f<\/strong> \u2b50\ufe0f <strong>Kai Meyer |<\/strong> DE |<a href=\"https:\/\/alexs-and-books.de\/reading\/kai-meyer-die-wasserweber\/?customize_changeset_uuid=16598e6e-f802-4e85-8d62-b6106f7f4d7b\" target=\"_blank\" rel=\"noopener\"> Die Wasserweber<\/a> (Band 3 von 3)<\/p>\n<p>\u2714\ufe0f <strong>Kate White<\/strong> | DE | <a href=\"https:\/\/alexs-and-books.de\/reading\/kate-white-luege-nie\/?customize_changeset_uuid=16598e6e-f802-4e85-8d62-b6106f7f4d7b\" target=\"_blank\" rel=\"noopener\">L\u00fcge Nie!<\/a><\/p>\n<p><strong>\u2714\ufe0f Mona Kasten<\/strong> | DE | <a href=\"https:\/\/alexs-and-books.de\/reading\/mona-kasten-maxton-hall-save-us\/?customize_changeset_uuid=16598e6e-f802-4e85-8d62-b6106f7f4d7b\" target=\"_blank\" rel=\"noopener\">Maxton Hall: Save Us (Band 3 von 3)<\/a><\/p>\n<p><strong>\u2714\ufe0f Bianca Iosivoni<\/strong> | <a href=\"https:\/\/alexs-and-books.de\/reading\/bianca-iosivoni-twisted-fate-wenn-magie-erwacht-1\/?customize_changeset_uuid=16598e6e-f802-4e85-8d62-b6106f7f4d7b\" target=\"_blank\" rel=\"noopener\">Twisted Fate \u2013 Wenn Magie erwacht<\/a> (Band 1 von 2)<\/p>\n<p><strong>\u2714\ufe0f Mona Kasten<\/strong> | DE | <a href=\"https:\/\/alexs-and-books.de\/reading\/mona-kasten-maxton-hall-save-you-2\/?customize_changeset_uuid=16598e6e-f802-4e85-8d62-b6106f7f4d7b\" target=\"_blank\" rel=\"noopener\">Maxton Hall &#8211; Save you (Band 2 von 3)<\/a><\/p>\n<p>\u274c <strong>J\u00f3n Atli J\u00f3nasson<\/strong> | DE | Schmerz<\/p>\n<p><strong>\u274c Lisa Kirsch<\/strong> | DE | Querbeet ins Gl\u00fcck<\/p>\n<p><strong>\u274c E. L. James<\/strong> | DE |\u00a0 Fifty Shades Of Grey &#8211; befreite Lust (Band 3 von 3)<\/p>\n<h3>R\u00fcckblick<\/h3>\n<p data-start=\"0\" data-end=\"227\">Tats\u00e4chlich ist der Februar \u2013 trotz des kurzen Monats \u2013 eher \u00fcppig ausgefallen. Es ergaben sich viele Gelegenheiten zum Lesen, und diese wurden nat\u00fcrlich prompt genutzt. Acht B\u00fccher, von denen vier sogar 5-Sterne-Reads waren.<\/p>\n<p data-start=\"229\" data-end=\"322\" data-is-last-node=\"\" data-is-only-node=\"\">Meinen SuB konnte ich betr\u00e4chtlich abbauen, sodass auch einige neue B\u00fccher einziehen durften.<\/p>\n<h4>Entt\u00e4uschung des Monats<\/h4>\n<p data-start=\"0\" data-end=\"237\">Ganz klar die <em data-start=\"14\" data-end=\"27\">Maxton-Hall<\/em>-Trilogie. Die Reihe wurde f\u00fcr mich von Band zu Band immer schlechter, und irgendwann \u00fcberflog ich ganze Seiten. Wahrscheinlich h\u00e4tte der Serie eine Dilogie besser getan \u2013 mit weniger Charaktersicht-Kapiteln.<\/p>\n<p data-start=\"239\" data-end=\"637\">Auch <em data-start=\"244\" data-end=\"268\">Fifty Shades of Grey 3<\/em> entpuppte sich als Entt\u00e4uschung. Bis Seite 100 habe ich durchgehalten und dann die Regisseure des dritten Films regelrecht gelobt: Anfangs habe ich mich \u00fcber die zusammengeklatschten Szenen im Film beschwert, aber wie sich herausstellte, konnte man gar nicht mehr verwenden \u2013 diese \u201ezusammengeklatschten Szenen\u201c waren bereits das Beste, was das Buch zu bieten hatte.<\/p>\n<p data-start=\"639\" data-end=\"989\" data-is-last-node=\"\" data-is-only-node=\"\"><em data-start=\"639\" data-end=\"659\">Querbeet ins Gl\u00fcck<\/em> fing sehr gut an, doch die Vielzahl an verschiedenen Lebensstilen, die thematisiert wurden, war mir dann doch zu viel. Schade. Ich war kurzzeitig am \u00dcberlegen, wegen der Nebencharaktere weiterzulesen \u2013 die waren wirklich grandios und mein insgeheimer 5-Sterne-Read. Doch nach der H\u00e4lfte habe ich das Buch schlie\u00dflich abgebrochen.<\/p>\n<h4>\u00dcberraschung des Monats<\/h4>\n<p>Twisted Fate fing fad an, wurde dann allerdings zu einem guten Read. Bin auf Band 2 gespannt.<\/p>\n<p>&nbsp;<\/p>\n<h3>Preiserh\u00f6hung bei der Schm\u00f6kerbox<\/h3>\n<p data-start=\"0\" data-end=\"92\">Die Schm\u00f6kerbox hat ihre Schm\u00f6kerliebe-Geb\u00fchr von 0,95 \u20ac auf 3,95 \u20ac angehoben. Ui ui ui&#8230; Bei den Bookblinddates sogar auf 5 \u20ac, weil 0,50 \u20ac wohl gespendet werden soll.<\/p>\n<p data-start=\"94\" data-end=\"502\" data-is-last-node=\"\">Tats\u00e4chlich habe ich das Abo deswegen momentan pausiert \u2013 mit der Intention, nur bei wirklich spannend klingenden Beschreibungen das jeweilige Buch zu holen (vornehmlich bei signierten B\u00fcchern o.\u00e4.). Grunds\u00e4tzlich verstehe ich die Begr\u00fcndung f\u00fcr die Erh\u00f6hung, aber zus\u00e4tzliche 3 \u20ac (4 \u20ac) l\u00e4ppern sich doch. 4 \u20ac (5 \u20ac) f\u00fcr ein Buch auszugeben, das ich gar nicht kenne, ist mir dann doch zu viel. Daf\u00fcr sind mir die Verpackung und das Lesezeichen einfach nicht wert. Ehrlichgesagt entt\u00e4uscht mich das etwas.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Lesegl\u00fcck Buchbox von Hugendubel<\/strong><\/h3>\n<p data-start=\"0\" data-end=\"84\">&#8230; aber ganz ohne ein \u00dcberraschungsbuch soll es dann doch erst einmal nicht sein.<\/p>\n<p data-start=\"86\" data-end=\"547\">Wenn ich von einem Durchschnittspreis von etwa 17 \u20ac pro Buch ausgehe + 4 \u20ac (5 \u20ac) Schm\u00f6kerliebe-Geb\u00fchr, komme ich auf 21 \u20ac (22 \u20ac). Da erscheint mir die Buchklopfenbox mit 20 \u20ac f\u00fcr ein Buch irgendwie attraktiver. Daher probiere die Buchklopfenbox ab Februar 2025 erst einmal f\u00fcr drei Monate aus. Unattraktiv an diesem Abomodell fand ich bisher immer, dass die Bindung f\u00fcr mindestens drei Monate erfolgen muss \u2013 aber nun denn.<\/p>\n<p data-start=\"549\" data-end=\"599\" data-is-last-node=\"\"><strong>Edit nach Erhalt der ersten Box:<\/strong> das erste Buch kostet 18 \u20ac &#8211; w\u00e4ren in diesem Fall 2 \u20ac an ich nenne es mal &#8222;Servicegeb\u00fchr&#8220;. Das erste Buch musste ich leider auch direkt abbrechen, aber kann bei zuf\u00e4lligen B\u00fcchern nat\u00fcrlich passieren &#8211; und hier sind dann &#8222;nur&#8220; zus\u00e4tzlich 2\u20ac Fl\u00f6ten gegangen. Insgesamt habe ich mich sogar nun dazu entschieden, zus\u00e4tzlich zum &#8222;Spannungs&#8220;-Abo, auch das Unterhaltungs-Abo auszuprobieren. Die Unterhaltung g\u00f6nne ich mir gemeinsam mit meinem Lesebuddy reading_world95 (ich konnte sie erfolgreich zu diesem Abo anstiften \ud83d\ude00 )<\/p>\n<p>&nbsp;<\/p>\n<h3>Reado<\/h3>\n<p data-start=\"0\" data-end=\"310\">Irgendwie werde ich mit Reado nicht warm. Zuletzt habe ich ein Buch als abgeschlossen markiert, das auch unter der Kategorie \u201eabgeschlossen\u201c gef\u00fchrt wird, aber dennoch nicht in der Lesestatistik auftaucht. Ich habe es bereits gel\u00f6scht und hin und her verschoben \u2013 irgendwann wurde es dann angezeigt.<\/p>\n<p data-start=\"312\" data-end=\"636\" data-is-last-node=\"\">Au\u00dferdem m\u00fcsste ich akribisch meine gelesenen Seiten t\u00e4glich tracken, damit die Statistik nicht verf\u00e4lscht wird. Da ist mir mein Lesejournal tausendmal lieber. \ud83d\ude05 Reado bleibt vorerst \u2013 allein schon wegen der Buddyreads und meiner Aussortiert-Liste \u2013, aber zum Tracken finde ich die App f\u00fcr mich pers\u00f6nlich eher unbrauchbar.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3>Neuzug\u00e4nge<\/h3>\n<p><strong>B\u00fccher<\/strong><\/p>\n<p><strong> Bianca Iosivoni<\/strong> | Twisted Fate \u2013 Wenn Liebe zerst\u00f6rt (Band 2 von 2)<\/p>\n<p><strong>\u2714\ufe0f \u2b50\ufe0f Tr\u00edona Walsh<\/strong> | DE | Schneesturm \/ Buddyread mit @reading_world95<\/p>\n<p><strong>Tr\u00edona Walsch<\/strong> | DE | Nachtwald \/ Buddyread mit @reading_world95<\/p>\n<p><strong>Anthony Horowitz<\/strong> | DE | Der Tote aus Zimmer 12<\/p>\n<p><strong>Benjamin Stevenson<\/strong> | DE | Die m\u00f6rderischen Cunninghams<\/p>\n<p><strong>\u274c J\u00f3n Atli J\u00f3nasson<\/strong> | DE | Schmerz<\/p>\n<p><strong>Elizabeth Lim<\/strong> | DE | Der Fluch der Schwestern (Band 0 von 2)<\/p>\n<p><strong>C.L. Miller<\/strong> | DE | Der falsche Vogel<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mein Februar Lesemonat ist da und ein bisschen Geplauder \u00fcber die Schm\u00f6kerbox (Preiserh\u00f6hung) und was&#8230;<\/p>\n","protected":false},"author":1,"featured_media":190,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-37","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lesemonat"],"_links":{"self":[{"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/posts\/37","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/comments?post=37"}],"version-history":[{"count":4,"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/posts\/37\/revisions"}],"predecessor-version":[{"id":213,"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/posts\/37\/revisions\/213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/media\/190"}],"wp:attachment":[{"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/media?parent=37"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/categories?post=37"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alexs-and-books.de\/reading\/wp-json\/wp\/v2\/tags?post=37"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}